{"id":56627,"date":"2026-02-10T13:44:40","date_gmt":"2026-02-10T12:44:40","guid":{"rendered":"https:\/\/www.crowdfarming.com\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/"},"modified":"2026-03-19T13:48:00","modified_gmt":"2026-03-19T12:48:00","slug":"gibt-es-eine-ethische-art-fleisch-zu-produzieren","status":"publish","type":"podcast","link":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/","title":{"rendered":"Gibt es eine ethische Art, Fleisch zu produzieren?"},"content":{"rendered":"","protected":false},"author":174,"featured_media":57386,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[],"class_list":["post-56627","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?<\/title>\n<meta name=\"description\" content=\"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&amp;B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?\" \/>\n<meta property=\"og:description\" content=\"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&amp;B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/\" \/>\n<meta property=\"og:site_name\" content=\"WTF\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T12:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2026\/02\/DSC02489-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/\",\"url\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/\",\"name\":\"WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DSC02489-1-scaled.jpg\",\"datePublished\":\"2026-02-10T12:44:40+00:00\",\"dateModified\":\"2026-03-19T12:48:00+00:00\",\"description\":\"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DSC02489-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/DSC02489-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/podcast\\\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crowdfarming.com\\\/de\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gibt es eine ethische Art, Fleisch zu produzieren?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTF\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?","description":"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/","og_locale":"de_DE","og_type":"article","og_title":"WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?","og_description":"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.","og_url":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/","og_site_name":"WTF","article_modified_time":"2026-03-19T12:48:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2026\/02\/DSC02489-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/","url":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/","name":"WTField?! Podcast:Gibt es eine ethische Art, Fleisch zu produzieren?","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/#primaryimage"},"image":{"@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2026\/02\/DSC02489-1-scaled.jpg","datePublished":"2026-02-10T12:44:40+00:00","dateModified":"2026-03-19T12:48:00+00:00","description":"In dieser Episode sprachen wir mit den Landwirten Benedikt B\u00f6sel (Gut&B\u00f6sel) und Alfonso Chico de Guzm\u00e1n (La Junquera) dar\u00fcber, was es in der Praxis wirklich bedeutet, eine Kuh aufzuziehen \u2013 und sie zu schlachten.","breadcrumb":{"@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/#primaryimage","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2026\/02\/DSC02489-1-scaled.jpg","contentUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2026\/02\/DSC02489-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/podcast\/gibt-es-eine-ethische-art-fleisch-zu-produzieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crowdfarming.com\/de\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"Gibt es eine ethische Art, Fleisch zu produzieren?"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTF","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/podcast\/56627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/comments?post=56627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/media\/57386"}],"wp:attachment":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/media?parent=56627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/de\/wp-json\/wp\/v2\/categories?post=56627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}