{"id":22682,"date":"2025-08-18T11:21:29","date_gmt":"2025-08-18T09:21:29","guid":{"rendered":"https:\/\/www.crowdfarming.com\/podcast\/planet-score-impacto-alimentario\/"},"modified":"2026-02-02T15:45:20","modified_gmt":"2026-02-02T14:45:20","slug":"planet-score-impacto-alimentario","status":"publish","type":"podcast","link":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/podcast\/planet-score-impacto-alimentario\/","title":{"rendered":"Hacer visible el impacto de nuestras elecciones alimentarias: conversaci\u00f3n con Sabine Bonnot de Planet-score"},"content":{"rendered":"\r\n<p>En este episodio de <em>What the Field?!<\/em>, hablamos con Sabine Bonnot, presidenta de Planet-score, sobre c\u00f3mo su sistema de etiquetado ayuda a los consumidores a comprender mejor el impacto medioambiental de lo que compran \u2014 y por qu\u00e9 algunos tipos de informaci\u00f3n importan m\u00e1s que otros.<br \/><br \/><\/p>\r\n\r\n\r\n\r\n<p>Bas\u00e1ndose en investigaciones realizadas en supermercados de toda Europa, Sabine explica por qu\u00e9 los compradores desconf\u00edan de las puntuaciones simplificadas y agregadas, y c\u00f3mo la transparencia en temas como el uso de pesticidas, la biodiversidad, el bienestar animal y los m\u00e9todos de producci\u00f3n puede guiar hacia elecciones m\u00e1s sostenibles.<br \/><br \/><\/p>\r\n\r\n\r\n\r\n<p>Sabine comparte sus reflexiones sobre:<br \/><br \/><\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Por qu\u00e9 el impacto clim\u00e1tico suele tener menos peso en las decisiones de compra de alimentos<\/li>\r\n<li>C\u00f3mo las etiquetas detalladas pueden impulsar pr\u00e1cticas agr\u00edcolas beneficiosas para la naturaleza<\/li>\r\n<li>El papel de una comunicaci\u00f3n clara en la creaci\u00f3n de confianza entre agricultores y consumidores<br \/><br \/><br \/><\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Esc\u00fachalo ahora en tu plataforma favorita o directamente a trav\u00e9s de este enlace:<br \/><br \/><\/p>\r\n<a href='https:\/\/www.buzzsprout.com\/1968536\/episodes\/17687151' target='_blank' class='btn-go-to' video-url='https:\/\/www.buzzsprout.com\/1968536\/episodes\/17687151'><p>Esc\u00fachalo en tu plataforma de audio<\/p><div class='icon'>\n\t\t\t\t\t\t<svg width='36' height='36' viewBox='0 0 36 36' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'>\n\t\t\t\t\t\t<path d='M11.6352 24.3598L24.3631 11.6319M24.3631 11.6319L15.8779 11.6319M24.3631 11.6319L24.3631 20.1172' stroke='#FAFAFA' stroke-width='3' stroke-linecap='round'\/>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t<\/div><\/a>\r\n\r\n\r\n","protected":false},"author":174,"featured_media":56120,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[],"class_list":["post-22682","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planet-score: hacer visible el impacto de lo que comemos<\/title>\n<meta name=\"description\" content=\"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planet-score: hacer visible el impacto de lo que comemos\" \/>\n<meta property=\"og:description\" content=\"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/\" \/>\n<meta property=\"og:site_name\" content=\"WTField?!\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T14:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/08\/sabine-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/\",\"url\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/\",\"name\":\"Planet-score: hacer visible el impacto de lo que comemos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sabine-3.png\",\"datePublished\":\"2025-08-18T09:21:29+00:00\",\"dateModified\":\"2026-02-02T14:45:20+00:00\",\"description\":\"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sabine-3.png\",\"contentUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/sabine-3.png\",\"width\":350,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/podcast\\\/planet-score-impacto-alimentario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crowdfarming.com\\\/es\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hacer visible el impacto de nuestras elecciones alimentarias: conversaci\u00f3n con Sabine Bonnot de Planet-score\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTField?!\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planet-score: hacer visible el impacto de lo que comemos","description":"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/","og_locale":"es_ES","og_type":"article","og_title":"Planet-score: hacer visible el impacto de lo que comemos","og_description":"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.","og_url":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/","og_site_name":"WTField?!","article_modified_time":"2026-02-02T14:45:20+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/08\/sabine-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/","url":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/","name":"Planet-score: hacer visible el impacto de lo que comemos","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/#primaryimage"},"image":{"@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/08\/sabine-3.png","datePublished":"2025-08-18T09:21:29+00:00","dateModified":"2026-02-02T14:45:20+00:00","description":"Planet-score ayuda a los consumidores a entender el impacto ambiental de sus compras y a tomar decisiones alimentarias m\u00e1s sostenibles y transparentes.","breadcrumb":{"@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/#primaryimage","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/08\/sabine-3.png","contentUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/08\/sabine-3.png","width":350,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/planet-score-impacto-alimentario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"Hacer visible el impacto de nuestras elecciones alimentarias: conversaci\u00f3n con Sabine Bonnot de Planet-score"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTField?!","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/podcast\/22682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/comments?post=22682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/media\/56120"}],"wp:attachment":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/media?parent=22682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/es\/wp-json\/wp\/v2\/categories?post=22682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}