{"id":33904,"date":"2018-10-22T00:00:00","date_gmt":"2018-10-21T22:00:00","guid":{"rendered":"https:\/\/www.crowdfarming.com\/non-categorise\/la-sobriete-heureuse-plat-du-jour-de-yasola\/"},"modified":"2026-05-06T11:40:35","modified_gmt":"2026-05-06T09:40:35","slug":"la-sobriete-heureuse-plat-du-jour-de-yasola","status":"publish","type":"post","link":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/","title":{"rendered":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola"},"content":{"rendered":"<p>Dans sa petite cabane \u00e0 la fronti\u00e8re de l\u2019Espagne, sans eau courante ni \u00e9lectricit\u00e9, Mertxe Perrugoria sert la cuisine la plus chaleureuse du Pays basque. Bienvenue \u00e0 la venta Yasola o\u00f9, depuis trois g\u00e9n\u00e9rations, les tranches de vie sont servies sans suppl\u00e9ment.<\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5439-768x512-1.jpg\" alt=\"La venta Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<p><em>Je viens \u00e0 Yasola depuis quarante-huit ans<\/em>, annonce fi\u00e8rement Michel en arrivant \u00e0 la cabane qui laisse \u00e9chapper un d\u00e9licieux fumet de poulet r\u00f4ti et de frites maison.\u00a0<em>Je monte tous les quinze jours \u00e0 la Rhune, en redescendant je m\u2019arr\u00eate ici pour d\u00e9jeuner.\u00a0<\/em>Avant de passer \u00e0 table, l&#8217;octog\u00e9naire s\u2019offre une brass\u00e9e de paysages. D\u2019un c\u00f4t\u00e9 la baie de Saint-Jean de Luz, de l\u2019autre la Rhune qui domine le Pays basque du haut de ses 905 m\u00e8tres d\u2019altitude.<em> C\u2019est toujours aussi beau m\u00eame si, imperceptiblement, de plus en plus de constructions viennent miter le paysage, <\/em>confie le randonneur.<\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5583-768x512-1.jpg\" alt=\"Habitu\u00e9 de Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<h3>Sagrada familia<\/h3>\n<p>Comme s\u2019il avait toujours \u00e9t\u00e9 de la famille, Michel s\u2019installe \u00e0 l\u2019une des tables \u00e0 l\u2019int\u00e9rieur, bient\u00f4t rejoint par des inconnus de passage. Aujourd\u2019hui, il fait froid, le vent souffle fort dans les feuilles des platanes qui entourent la bicoque solidement arrim\u00e9e \u00e0 la montagne. Rares sont les audacieux \u00e0 s\u2019installer sur l\u2019une des grandes tables de la terrasse o\u00f9 est affich\u00e9 le menu du jour : omelette au piment, poulet fermier, agneau et frites. Des produits 100 % espagnols que Mertxe pr\u00e9-cuisine dans sa ferme de Mendiondo \u00e0 20 minutes de piste de l\u00e0 avant de les monter en 4&#215;4. <em>Je commence \u00e0 travailler \u00e0 6 heures du matin,<\/em>\u00a0confie-t-elle dans un large sourire qui ne la quitte jamais.<\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5502-768x512-1.jpg\" alt=\"Mise en route d&#039;un groupe \u00e9lectrog\u00e8ne \u00e0 Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<p>La suite se passe dans sa cuisine de Yasola. L\u2019eau provient d\u2019une source de la montagne, la lumi\u00e8re des plafonniers du groupe \u00e9lectrog\u00e8ne qui a bien failli co\u00fbter la vie de Mertxe. <em>Il y a treize ans, le 3 septembre exactement, le groupe a pris feu. J\u2019\u00e9tais \u00e0 l\u2019int\u00e9rieur, cern\u00e9e par les flammes,<\/em> explique la ma\u00eetresse de maison dont les marques de br\u00fblure sur les bras viennent \u00e9tayer ses dires. <em>Le 18 d\u00e9cembre, on a r\u00e9ouvert.\u00a0Il ne me serait jamais venu \u00e0 l\u2019id\u00e9e de d\u00e9crocher.<\/em><\/p>\n<p>Sur les murs de la cabane en bois, une peinture d\u2019anges gardiens \u00e9loigne depuis le mauvais sort. <em>Quelques jours apr\u00e8s la r\u00e9ouverture, les habitu\u00e9s m\u2019ont fait une \u00e9norme surprise. Ils sont tous mont\u00e9s \u00e0 Yasola et m\u2019ont offert ce tableau<\/em>.<\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5543-768x512-1.jpg\" alt=\"Mertxe dans sa cuisine de Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<h3>Nourrir de bonheur<\/h3>\n<p>Apr\u00e8s l\u2019incendie, la venta construite dans les ann\u00e9es 1940 par un d\u00e9serteur de Saint-P\u00e9e-sur-Nivelle a \u00e9t\u00e9 reb\u00e2tie \u00e0 l\u2019identique. Soit une succession de pi\u00e8ces en enfilade : r\u00e9serve, cuisine, bar, salle de restauration, terrasse. Dans un coin du b\u00e2timent se trouve une salle de repos o\u00f9 l\u2019\u00e9quipe mange avant et apr\u00e8s le service. <em>Mertxe\u00a0nous soigne,<\/em> explique Jocelyne, hier assistante sociale. <em>Chaque \u00e9t\u00e9, je prends 3 kilos.<\/em>\u00a0La Bayonnaise en reconversion adore monter donner un coup de main, m\u00eame quand il y a plus de 100 couverts \u00e0 servir et autant d\u2019assiettes \u00e0 laver \u00e0 la main en fin de journ\u00e9e, m\u00eame les jours de pluie.<\/p>\n<p><em>J\u2019ai travaill\u00e9 trois semaines dans un restaurant \u00e0 Bayonne. Chaque matin, j\u2019avais la boule au ventre. Ici, il y a une grande proximit\u00e9 entre nous, chacun fait attention \u00e0 l\u2019autre.<\/em>\u00a0Sentiment partag\u00e9 par Xandik, fid\u00e8le coll\u00e8gue depuis neuf ans, qui porte toujours des chaussettes d\u00e9pareill\u00e9es et arbore le sourire communicatif de l\u2019\u00e9quipe Yasola. <em>Les gens qui travaillent ici restent et reviennent, <\/em>explique Mertxe<em>. Yasola, c\u2019est une famille.<\/em><\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5591-768x512-1.jpg\" alt=\"Clientes de la venta Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<p>Michel fait ind\u00e9niablement partie de cette tribu et, \u00e0 l\u2019instar du grand oncle, raconte encore et encore l\u2019histoire du lieu. <em>La premi\u00e8re fois que je suis venu \u00e0 Yasola en 1970, quand je suis entr\u00e9 dans la cabane, tout le monde s\u2019est arr\u00eat\u00e9 de parler. Je venais de Normandie, on m\u2019avait pris pour un douanier.\u00a0<\/em><em>La venta \u00e9tait autrefois un lieu de contrebande o\u00f9 l\u2019on \u00e9changeait des produits interdits,<\/em> explique Mertxe qui tient l\u2019information de sa belle-m\u00e8re Carmen qui elle-m\u00eame l\u2019a r\u00e9colt\u00e9e aupr\u00e8s de sa m\u00e8re Paquit, \u00e0 l&#8217;origine de l&#8217;ouverture de la venta en 1967. <em>Les espagnols venaient ici la nuit \u00e9changer des roulements \u00e0 billes de camion contre des cigarettes et de l\u2019alcool,<\/em>\u00a0poursuit Michel.<\/p>\n<p>De la d\u00e9bauche \u00e0 bas prix pour les Fran\u00e7ais, des produits introuvables pour les Espagnols, pendant longtemps, Yasola forme avec des dizaines de ventas un large r\u00e9seau d\u2019\u00e9changes illicites masqu\u00e9s par un bon repas.\u00a0\u00a0<em>En r\u00e9alit\u00e9, les gens mangeaient surtout des sardines et du thon en bo\u00eete,<\/em>\u00a0rapporte Mertxe.<\/p>\n<div class=\"wrapper-p\"><img src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2018\/10\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5613-768x512-1.jpg\" alt=\"L&#039;un des repas de la venta Yasola\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" class=\"attachment-medium_large size-medium_large\"><\/div>\n<p>Aujourd\u2019hui, Franco n\u2019est plus, les ventas sont sorties de la clandestinit\u00e9. La plupart sont devenues de vastes zones commerciales sans charme o\u00f9 l\u2019on vient faire un plein d\u2019essence, de cigarettes et de sp\u00e9cialit\u00e9s plus ou moins <em>made in Espa\u00f1a<\/em>. Dans ce tourbillon d\u2019hyperconsommation, Yasola r\u00e9siste.\u00a0On y monte \u00e0 pied pour faire le plein de paysages, d\u2019authenticit\u00e9, de gentillesse et pour constater qu\u2019il n\u2019y a d\u00e9cid\u00e9ment pas meilleur que la simplicit\u00e9 cuisin\u00e9e avec le c\u0153ur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans sa petite cabane \u00e0 la fronti\u00e8re de l\u2019Espagne, sans eau courante ni \u00e9lectricit\u00e9, Mertxe Perrugoria sert la cuisine la plus chaleureuse du Pays basque. Bienvenue \u00e0 la venta Yasola o\u00f9, depuis trois g\u00e9n\u00e9rations, les tranches de vie sont servies sans suppl\u00e9ment. Je viens \u00e0 Yasola depuis quarante-huit ans, annonce fi\u00e8rement Michel en arrivant \u00e0 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[497],"tags":[3937,3936,3934],"class_list":["post-33904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sur-le-terrain","tag-venta-yasola","tag-generations","tag-pays-basque"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF\" \/>\n<meta property=\"og:description\" content=\"Dans sa petite cabane \u00e0 la fronti\u00e8re de l\u2019Espagne, sans eau courante ni \u00e9lectricit\u00e9, Mertxe Perrugoria sert la cuisine la plus chaleureuse du Pays basque. Bienvenue \u00e0 la venta Yasola o\u00f9, depuis trois g\u00e9n\u00e9rations, les tranches de vie sont servies sans suppl\u00e9ment. Je viens \u00e0 Yasola depuis quarante-huit ans, annonce fi\u00e8rement Michel en arrivant \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/\" \/>\n<meta property=\"og:site_name\" content=\"WTF\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-21T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T09:40:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e9l\u00e8ne Binet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9l\u00e8ne Binet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/\"},\"author\":{\"name\":\"H\u00e9l\u00e8ne Binet\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/a98a6af909f2ed70c0b6adaf6b2ece35\"},\"headline\":\"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola\",\"datePublished\":\"2018-10-21T22:00:00+00:00\",\"dateModified\":\"2026-05-06T09:40:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/\"},\"wordCount\":895,\"image\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg\",\"keywords\":[\"venta yasola\",\"g\u00e9n\u00e9rations\",\"pays basque\"],\"articleSection\":[\"Sur le terrain\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/\",\"name\":\"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg\",\"datePublished\":\"2018-10-21T22:00:00+00:00\",\"dateModified\":\"2026-05-06T09:40:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/a98a6af909f2ed70c0b6adaf6b2ece35\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg\",\"contentUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Mertxe Perrugoria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/sur-le-terrain\\\/la-sobriete-heureuse-plat-du-jour-de-yasola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTF\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/a98a6af909f2ed70c0b6adaf6b2ece35\",\"name\":\"H\u00e9l\u00e8ne Binet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g\",\"caption\":\"H\u00e9l\u00e8ne Binet\"},\"description\":\"Son sourire est invincible mais sa vie semble impossible. H\u00e9l\u00e8ne \u00e9crit pour ce blog, pour des sites d'information alternatifs ou la presse traditionnelle ; elle publie des guides aussi diff\u00e9rents que \\\"Les arbres remarquables d'Is\u00e8re\\\" ou \\\"Belle et bio \u00e0 Paris\\\" ; elle g\u00e8re sa propre Ruche, l'une des premi\u00e8res et des plus grandes de France ; elle a trois enfants ; elle \u00e9l\u00e8ve un chat. Quand on y pense on perd haleine. Pas elle.\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/fr\\\/author\\\/helene\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/","og_locale":"fr_FR","og_type":"article","og_title":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF","og_description":"Dans sa petite cabane \u00e0 la fronti\u00e8re de l\u2019Espagne, sans eau courante ni \u00e9lectricit\u00e9, Mertxe Perrugoria sert la cuisine la plus chaleureuse du Pays basque. Bienvenue \u00e0 la venta Yasola o\u00f9, depuis trois g\u00e9n\u00e9rations, les tranches de vie sont servies sans suppl\u00e9ment. Je viens \u00e0 Yasola depuis quarante-huit ans, annonce fi\u00e8rement Michel en arrivant \u00e0 [&hellip;]","og_url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/","og_site_name":"WTF","article_published_time":"2018-10-21T22:00:00+00:00","article_modified_time":"2026-05-06T09:40:35+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg","type":"image\/jpeg"}],"author":"H\u00e9l\u00e8ne Binet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"H\u00e9l\u00e8ne Binet","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#article","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/"},"author":{"name":"H\u00e9l\u00e8ne Binet","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/a98a6af909f2ed70c0b6adaf6b2ece35"},"headline":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola","datePublished":"2018-10-21T22:00:00+00:00","dateModified":"2026-05-06T09:40:35+00:00","mainEntityOfPage":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/"},"wordCount":895,"image":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg","keywords":["venta yasola","g\u00e9n\u00e9rations","pays basque"],"articleSection":["Sur le terrain"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/","name":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola - WTF","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#primaryimage"},"image":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg","datePublished":"2018-10-21T22:00:00+00:00","dateModified":"2026-05-06T09:40:35+00:00","author":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/a98a6af909f2ed70c0b6adaf6b2ece35"},"breadcrumb":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#primaryimage","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg","contentUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/TL480_LRQDO_PAYSBASQUE_venta_yasola_181010_5485-1.jpg","width":2000,"height":1333,"caption":"Mertxe Perrugoria"},{"@type":"BreadcrumbList","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/sur-le-terrain\/la-sobriete-heureuse-plat-du-jour-de-yasola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"La sobri\u00e9t\u00e9 heureuse, plat du jour de Yasola"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTF","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/a98a6af909f2ed70c0b6adaf6b2ece35","name":"H\u00e9l\u00e8ne Binet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3125dbe3f14e3244d11b23b0f6ffaadc9f3df52fe96d24dba7ee0d80158754d5?s=96&d=mm&r=g","caption":"H\u00e9l\u00e8ne Binet"},"description":"Son sourire est invincible mais sa vie semble impossible. H\u00e9l\u00e8ne \u00e9crit pour ce blog, pour des sites d'information alternatifs ou la presse traditionnelle ; elle publie des guides aussi diff\u00e9rents que \"Les arbres remarquables d'Is\u00e8re\" ou \"Belle et bio \u00e0 Paris\" ; elle g\u00e8re sa propre Ruche, l'une des premi\u00e8res et des plus grandes de France ; elle a trois enfants ; elle \u00e9l\u00e8ve un chat. Quand on y pense on perd haleine. Pas elle.","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/author\/helene\/"}]}},"_links":{"self":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/33904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/comments?post=33904"}],"version-history":[{"count":1,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/33904\/revisions"}],"predecessor-version":[{"id":61956,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/33904\/revisions\/61956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/media\/33905"}],"wp:attachment":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/media?parent=33904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/categories?post=33904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/fr\/wp-json\/wp\/v2\/tags?post=33904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}