{"id":56138,"date":"2025-10-10T12:44:27","date_gmt":"2025-10-10T10:44:27","guid":{"rendered":"https:\/\/www.crowdfarming.com\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/"},"modified":"2026-02-02T14:57:08","modified_gmt":"2026-02-02T13:57:08","slug":"collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende","status":"publish","type":"podcast","link":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/","title":{"rendered":"Collegare la salute del suolo e la salute umana con Raiza Rezende"},"content":{"rendered":"&#13;\n<p>Questo episodio analizza in che modo le pratiche agricole influenzano la qualit\u00e0 nutrizionale degli alimenti &#8211; e cosa servirebbe per rendere questa conoscenza utile nel settore sanitario? La nostra ospite \u00e8 <strong>Raiza Rezende<\/strong>, cofondatrice della <strong>RHEA &#8211; <\/strong><a href=\"https:\/\/www.rheaeu.com\/\"><strong>Regenerative Healthcare European Association<\/strong><\/a>un&#8217;organizzazione che si occupa di formazione, ricerca e politica per collegare agricoltura e sanit\u00e0. <br\/><br\/><\/p>&#13;\n&#13;\n<p><strong>In questo episodio ascolterai:<\/strong><br\/><br\/><br\/><\/p>&#13;\n&#13;\n<ul class=\"wp-block-list\">&#13;\n<li>Perch\u00e9 la salute del suolo e la salute umana sono collegate. Parliamo di <em>One Health, l&#8217;<\/em>idea che la salute del suolo, delle piante, degli animali e delle persone sia interconnessa, anche attraverso il microbioma. <\/li>&#13;\n<li>Colmare il divario tra aziende agricole e sanit\u00e0. La missione principale di RHEA \u00e8 quella di mettere in contatto il settore sanitario (medici, ospedali, dietologi) con l&#8217;agricoltura. <\/li>&#13;\n<li>A che punto \u00e8 la scienza. La densit\u00e0 di nutrienti \u00e8 un campo giovane; le prove sono in crescita ma non omogenee. Parliamo dell&#8217;esecuzione di studi pluriennali basati sui risultati e del perch\u00e9 i risultati devono essere letti con sfumature.  <\/li>&#13;\n<li>Come misurare la &#8220;densit\u00e0 di nutrienti&#8221; senza clamore. Dai pannelli di laboratorio ai parametri di riferimento specifici per le colture (pomodori contro pomodori), e perch\u00e9 il disegno del campionamento conta pi\u00f9 degli slogan. <\/li>&#13;\n<\/ul>&#13;\n<a href='https:\/\/www.buzzsprout.com\/1968536\/episodes\/17988061' target='_blank' class='btn-go-to' video-url='https:\/\/www.buzzsprout.com\/1968536\/episodes\/17988061'><p>Listen on your audio platform<\/p><div class='icon'>\n\t\t\t\t\t\t<svg width='36' height='36' viewBox='0 0 36 36' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'>\n\t\t\t\t\t\t<path d='M11.6352 24.3598L24.3631 11.6319M24.3631 11.6319L15.8779 11.6319M24.3631 11.6319L24.3631 20.1172' stroke='#FAFAFA' stroke-width='3' stroke-linecap='round'\/>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t<\/div><\/a>&#13;\n","protected":false},"author":174,"featured_media":56130,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[],"class_list":["post-56138","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suolo e salute umana: Raiza Rezende collega le aziende agricole e l&#039;assistenza sanitaria<\/title>\n<meta name=\"description\" content=\"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suolo e salute umana: Raiza Rezende collega le aziende agricole e l&#039;assistenza sanitaria\" \/>\n<meta property=\"og:description\" content=\"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/\" \/>\n<meta property=\"og:site_name\" content=\"WTF\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T13:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/raiza-foto-perfil-profile-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/\",\"name\":\"Suolo e salute umana: Raiza Rezende collega le aziende agricole e l'assistenza sanitaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/raiza-foto-perfil-profile-scaled.jpg\",\"datePublished\":\"2025-10-10T10:44:27+00:00\",\"dateModified\":\"2026-02-02T13:57:08+00:00\",\"description\":\"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/raiza-foto-perfil-profile-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/raiza-foto-perfil-profile-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/es\\\/what-the-field\\\/podcast\\\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crowdfarming.com\\\/it\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collegare la salute del suolo e la salute umana con Raiza Rezende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTF\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suolo e salute umana: Raiza Rezende collega le aziende agricole e l'assistenza sanitaria","description":"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crowdfarming.com\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/","og_locale":"it_IT","og_type":"article","og_title":"Suolo e salute umana: Raiza Rezende collega le aziende agricole e l'assistenza sanitaria","og_description":"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.","og_url":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/","og_site_name":"WTF","article_modified_time":"2026-02-02T13:57:08+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/raiza-foto-perfil-profile-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/","url":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/","name":"Suolo e salute umana: Raiza Rezende collega le aziende agricole e l'assistenza sanitaria","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/#primaryimage"},"image":{"@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/raiza-foto-perfil-profile-scaled.jpg","datePublished":"2025-10-10T10:44:27+00:00","dateModified":"2026-02-02T13:57:08+00:00","description":"Il suolo e la salute umana sono collegati. Raiza Rezende spiega come possiamo iniziare a costruire ponti tra i sistemi alimentari e i sistemi sanitari.","breadcrumb":{"@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/#primaryimage","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/raiza-foto-perfil-profile-scaled.jpg","contentUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2025\/12\/raiza-foto-perfil-profile-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/laruchequiditoui.fr\/es\/what-the-field\/podcast\/collegare-la-salute-del-suolo-e-la-salute-umana-con-raiza-rezende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crowdfarming.com\/it\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"Collegare la salute del suolo e la salute umana con Raiza Rezende"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTF","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/podcast\/56138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/comments?post=56138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/media\/56130"}],"wp:attachment":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/media?parent=56138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/categories?post=56138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}