{"id":51409,"date":"2021-03-03T13:41:49","date_gmt":"2021-03-03T12:41:49","guid":{"rendered":"https:\/\/www.crowdfarming.com\/senza-categoria\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/"},"modified":"2025-12-22T21:03:27","modified_gmt":"2025-12-22T20:03:27","slug":"lagroecologia-e-la-chiave-per-la-transizione-ecologica","status":"publish","type":"post","link":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/","title":{"rendered":"L&#8217;agroecologia \u00e8 la chiave per la transizione ecologica?"},"content":{"rendered":"<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">L&#8217;agroecologia \u00e8 allo stesso tempo una disciplina scientifica, un movimento sociale e un insieme di pratiche agricole.<\/span> <span class=\"\" title=\"\">\u00c8 l&#8217;ecologia adattata all&#8217;agricoltura.<\/span> <span class=\"\" title=\"\">In effetti, \u00e8 l&#8217;<strong>agricoltura di domani<\/strong>, come <\/span><\/span><a href=\"https:\/\/news.un.org\/fr\/story\/2018\/04\/1010271\">ufficialmente riconosciuto dalle Nazioni Unite nel 2018<\/a>.<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7319 size-large\" src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/12\/agroecologia-1024x683.jpg\" alt=\"api e agroecologia\" width=\"640\" height=\"427\" \/><em>Le api, alleate alate dell&#8217;agroecologia. \u00a9Thomas Louapre<\/em><\/p>\n<hr \/>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Ma di cosa si tratta? L&#8217;<strong>agroecologia<\/strong> si basa sugli strumenti forniti dalla natura (come gli impollinatori che trasformano i fiori in frutti) per <strong>crescere, produrre e allevare preservando l&#8217;ambiente.<\/strong><\/span> Ma n<span class=\"\" title=\"\">on solo. L&#8217;ambiente viene anche arricchito perch\u00e9, a lungo termine, si difendono le sue capacit\u00e0 di rinnovamento e la sua resilienza, in modo da metterlo al riparo dalle catastrofi climatiche.<\/span> <span class=\"\" title=\"\">Catastrofi in parte innescate da &#8230; un&#8217;agricoltura praticata in modo intensivo per settant&#8217;anni.<\/span><\/span><\/p>\n<hr \/>\n<h2><strong>Equivale a praticare il biologico?<\/strong><\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Il termine <strong>agroecologia<\/strong> \u00e8 ancora poco conosciuto rispetto al concetto di agricoltura biologica.<\/span> <span class=\"\" title=\"\">Le due nozioni sono correlate, ma non sono sinonimi.<\/span> <span class=\"\" title=\"\">Innanzitutto, attenzione: <strong>l&#8217;agroecologia non \u00e8 un&#8217;etichetta!<\/strong><\/span> <span class=\"\" title=\"\">Non si basa su specifiche ma su <strong>principi<\/strong>; quindi, \u00e8 pi\u00f9 vaga e lascia spazio alle interpretazioni.<\/span> <span class=\"\" title=\"\">Per molti specialisti, l&#8217;agroecologia non proibisce completamente le <strong>sostanze chimiche<\/strong>, ma mira a ridurne l&#8217;uso o, addirittura, a farne completamente a meno.<\/span><span title=\"\"> Per altri, invece, i composti fitochimici sono vietati.<\/span><\/span><\/p>\n<hr \/>\n<h2>Com&#8217;\u00e8 una fattoria agroecologica?<\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">\u00c8 una fattoria <a href=\"http:\/\/blog.lalvearechedicesi.it\/2019\/09\/10\/astuzie-per-un-lombricompostiera-senza-mosche\/\" target=\"_blank\" rel=\"noopener\"><strong>con molti vermi<\/strong><\/a>, il migliore indicatore di una terra ricca!<\/span> Ma c<span class=\"\" title=\"\">i sono diversi aspetti da considerare.<\/span> <span class=\"\" title=\"\">Uno di questi \u00e8 la <strong>biodiversit\u00e0<\/strong>, basata, ad esempio, sulla reintroduzione del bosco (che costituisce un habitat meraviglioso per alcune specie spesso ausiliarie della coltivazione), sull&#8217;allevamento di alcuni bovini e la <strong>diversificazione dei semi<\/strong> (sinonimo<\/span> di <span class=\"\" title=\"\">robustezza e qualit\u00e0 nutrizionale nel piatto).<\/span><\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Secondo imperativo: il <strong>rispetto dei suoli<\/strong>.<\/span> <span class=\"\" title=\"\">Fertilizzazione verde, conservazione dell&#8217;umidit\u00e0, prodotti fitosanitari ridotti o addirittura eliminati a favore di metodi alternativi, ecc.<\/span> <span class=\"\" title=\"\">Il minimo in agroecologia \u00e8 la copertura del suolo, insiste <a href=\"https:\/\/www6.dijon.inra.fr\/umragroecologie\/Page-d-accueil\/Actualites\/Lionel-Ranjard-sur-France-Inter-Le-sol-un-patrimoine-a-proteger\">Lionel Ranjard<\/a>, direttore della ricerca presso l&#8217;INRA (Istituto nazionale di ricerca agricola) e specialista della materia.<\/span><\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Un <strong>terreno nudo<\/strong>\u00a0si impoverir\u00e0, sar\u00e0 sottoposto a tutte le aggressioni climatiche e privato del contributo organico delle piante.<\/span> <span class=\"\" title=\"\">La terra arata non mantiene pi\u00f9 la vita microbica sotterranea e rilascia il carbonio che dovrebbe immagazzinare per arricchirsi e fermare il riscaldamento.<\/span><\/span><span class=\"tlid-translation translation\" lang=\"it\"> <span class=\"\" title=\"\">Pertanto, la combinazione tra una cosiddetta agricoltura per la conservazione del suolo e l&#8217;agricoltura biologica, in effetti molto aggressiva per i terreni che sono spesso arati, pu\u00f2 essere interessante.<\/span><\/span><\/p>\n<hr \/>\n<p><a href=\"http:\/\/blog.lalvearechedicesi.it\/2021\/03\/03\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/agroecologia-suolo-2\/\" rel=\"attachment wp-att-7322\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7322\" src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/12\/agroecologia-suolo-1-1024x683.jpg\" alt=\"agroecologia in fattoria\" width=\"640\" height=\"427\" \/><\/a><em>L&#8217;agroecologia significa anche ricreare un ecosistema in fattoria. \u00a9Thomas Louapre<\/em><\/p>\n<hr \/>\n<h2>L&#8217;agroforestazione<\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\">Molti altri aspetti emergono dal quadro bucolico dell&#8217;agroecologia: diversificazione delle colture, ritorno della policoltura-bestiame, produzione di foraggi e proteine \u200b\u200bper nutrire il bestiame piuttosto che ricorrere all&#8217;importazione. L&#8217;agroecologia promuove anche le interazioni tra gli organismi ecosistemici, ad esempio attraverso l&#8217;<strong>agroforestazione<\/strong>. <\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"it\">Gli <strong>alberi<\/strong> fanno molte cose: bloccano il sole troppo intenso (o semplicemente forniscono ombra al bestiame e alle piante basse) e il vento, catturano meglio le precipitazioni attraverso le loro radici, nutrono e tengono compatto il suolo. I loro rami ospitano uccelli che riducono gli attacchi degli insetti e le loro foglie, cadendo a terra, forniscono <strong>biomassa<\/strong>, come le loro radici che si spezzano sottoterra. In breve, sviluppano un <strong>ecosistema essenziale<\/strong>, sostiene l&#8217;agroecologa Linda Bedouet, autrice di <a href=\"https:\/\/www.laboutiquejardinmaison.fr\/29670-neo-paysannes.html\"><i>Les N\u00e9o-Paysannes<\/i><\/a><i>,\u00a0<\/i> e creano la sua <a href=\"https:\/\/www.laboutiquejardinmaison.fr\/18301-creer-sa-micro-ferme-permaculture-et-agroecologie.html\">micro-fattoria: Permacultura e Agroecologia<\/a> (edizioni Rustica).<\/span><\/p>\n<hr \/>\n<h4><a href=\"http:\/\/blog.lalvearechedicesi.it\/2018\/05\/21\/agroforestazione-stesso-terreno-doppio-vantaggio\/\" target=\"_blank\" rel=\"noopener\">Agroforestazione: stesso terreno, doppio vantaggio<\/a><\/h4>\n<hr \/>\n<p><a href=\"http:\/\/blog.lalvearechedicesi.it\/2021\/03\/03\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/animale-e-pianta\/\" rel=\"attachment wp-att-7324\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7324\" src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/12\/animale-e-pianta-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" \/><\/a><em>Animale e piante, insieme per coltivare meglio \u00a9Thomas Louapre<\/em><\/p>\n<hr \/>\n<h2>Quanti agricoltori abbracciano l&#8217;agroecologia?<\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">\u00c8 impossibile fornire una cifra precisa, poich\u00e9 ogni azienda agricola pu\u00f2 avere alcuni aspetti agroecologici e c&#8217;\u00e8 confusione sulle definizioni.<\/span> <span class=\"\" title=\"\">L&#8217;agroecologia \u00e8 attualmente praticata su superfici limitate, come <strong>micro-fattorie<\/strong> o strutture leggermente pi\u00f9 grandi.<\/span> <span title=\"\">Perch\u00e9 l&#8217;idea, in definitiva, \u00e8 l&#8217;<strong>autonomia alimentare<\/strong> dell&#8217;agricoltore per ottenere la <strong>sovranit\u00e0 alimentare<\/strong> di un territorio.<\/span> <span class=\"\" title=\"\">Tuttavia, ritiene Lionel Ranjard, <em>l&#8217;agroecologia non \u00e8 solo a livello locale.<\/em><\/span>\u00a0<span class=\"\" title=\"\"><em>Tecnicamente, pu\u00f2 fornire una produzione su grandi aree<\/em>, per garantire una vasta rete di distribuzione.<\/span><\/span><\/p>\n<hr \/>\n<h2><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Qual \u00e8 il posto di uomini e donne in questo progetto?<\/span><\/span><\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\"><em>L&#8217;agroecologia ha una forte dimensione umana<\/em>, afferma Linda Bedouet.<\/span> <em><span class=\"\" title=\"\">Da cosa riteniamo che una fattoria, che \u00e8 diventata un&#8217;impresa, <strong>rimanga umana<\/strong>?<\/span> <span class=\"\" title=\"\">Se l&#8217;agricoltore diventa nuovamente un ingranaggio, dov&#8217;\u00e8 la coerenza e la sostenibilit\u00e0?<\/span> <\/em><span class=\"\" title=\"\"><em>I puristi si pongono queste domande<\/em>.<\/span> <span class=\"\" title=\"\">Soprattutto perch\u00e9 le <strong>aziende agricole<\/strong> tendono a crescere quando i professionisti agricoli sono sempre meno e pi\u00f9 distanti dai loro campi.<\/span> <span title=\"\">Un fenomeno che favorisce l&#8217;uso di risorse non naturali per facilitare il trattamento delle colture.<\/span> <em><span title=\"\">Con l&#8217;agroecologia, gli agricoltori tornano ad essere autonomi.<\/span> <\/em><span title=\"\"><em>Stanchi di essere a pezzi, vogliono pensare e trovare un significato nel loro lavoro<\/em>, afferma Lionel Ranjard.<\/span><\/span><\/p>\n<hr \/>\n<p><a href=\"http:\/\/blog.lalvearechedicesi.it\/2021\/03\/03\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/fattoria\/\" rel=\"attachment wp-att-7328\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7328\" src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/12\/fattoria-1024x683.jpg\" alt=\"contadino in fattoria\" width=\"640\" height=\"427\" \/><\/a><em>Autonomia: la base dell&#8217;agroecologia. \u00a9Thomas Louapre<\/em><\/p>\n<hr \/>\n<h2><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">L&#8217;agroecologia \u00e8 come la permacultura?<\/span><\/span><\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Il loro punto comune \u00e8 l&#8217;<strong>approccio sistemico e globale<\/strong>.<\/span> <span class=\"\" title=\"\">La <strong>permacultura<\/strong> \u00e8 pi\u00f9 ampia e si applica ad altre aree della vita di tutti i giorni: salute, valute, istruzione, costruzione di habitat, ecc.<\/span> <span class=\"\" title=\"\">L&#8217;agroecologia rimane <strong>limitata all&#8217;agricoltura e al cibo.<\/strong><\/span><\/span><\/p>\n<hr \/>\n<h2>Chi c&#8217;\u00e8 dietro?<\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Le sue radici, latinoamericane, sono socio-politiche e nascono dal movimento contadino <strong><a href=\"http:\/\/www.assorurale.it\/la_via_campesina.html\">Via Campesina<\/a><\/strong>.<\/span> <span class=\"\" title=\"\">L&#8217;agroecologia si oppone all&#8217;attuale sistema di produzione, ereditato dalla rivoluzione verde, che \u00e8 destinato a esaurirsi e <strong>non pu\u00f2 alimentare all&#8217;infinito l&#8217;insaziabile mercato di consumo.<\/strong><\/span> <span title=\"\">Nel 1995, Miguel Altieri, insieme a <a href=\"https:\/\/www.researchgate.net\/publication\/233139201_Integrating_Agroecological_Processes_into_Cropping_Systems_Research\">Stephen Gliessman<\/a>, hanno dato le prime definizioni di agroecologia.<\/span> <span class=\"\" title=\"\">Altieri aveva stabilito cinque principi; il <a href=\"https:\/\/www.colibris-lemouvement.org\/\">movimento di Colibris Pierre Rabhi<\/a>, incarnazione dell&#8217;agroecologia francese, ne riconosce dodici.<\/span> <span class=\"\" title=\"\">Se il significato dell&#8217;agroecologia \u00e8 aperto ed \u00e8 fonte di dibattito, questi principi costituiscono una base comune.<\/span><\/span><\/p>\n<hr \/>\n<h2><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">Un passo indietro o un&#8217;innovazione?<\/span><\/span><\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">L&#8217;agroecologia vuole ripartire dai tempi passati, ma al fine di <strong>soddisfare meglio le esigenze del mondo di oggi.<\/strong><\/span> <span class=\"\" title=\"\">Ha bisogno di ricerche per diventare un modello.<\/span> <span class=\"\" title=\"\">L&#8217;agroecologia \u00e8 un insieme di principi e pratiche che devono potersi adattare a un certo terreno, che presenta un <strong>ecosistema unico<\/strong> (geologia, risorse idriche, fauna &#8230;).<\/span> <span class=\"\" title=\"\"><em>Dobbiamo dotare gli agricoltori di semplici strumenti di misurazione per valutare le loro azioni<\/em>, sostiene Lionel Ranjard.<\/span><\/span><\/p>\n<hr \/>\n<p><a href=\"http:\/\/blog.lalvearechedicesi.it\/2021\/03\/03\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/transizione-ecologica\/\" rel=\"attachment wp-att-7330\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7330\" src=\"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2025\/12\/transizione-ecologica-1024x683.jpg\" alt=\"travaso di una pianta\" width=\"640\" height=\"427\" \/><\/a><em>Viva la transizione ecologica! \u00a9Thomas Louapre<\/em><\/p>\n<hr \/>\n<h2><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">L&#8217;agroecologia potr\u00e0 nutrire 9 miliardi di esseri umani?<\/span><\/span><\/h2>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span class=\"\" title=\"\">S\u00ec, afferma Philippe Pointereau senza mezzi termini, anche se sottolinea che questo metodo agricolo <strong>non produce tanto quanto quello convenzionale<\/strong>, almeno in Europa.<\/span> <span class=\"\" title=\"\">Il direttore della divisione agroambientale di Solagro \u00e8 stato coautore di uno degli unici report previsionali sull&#8217;argomento e ha seguito uno scenario di tendenza. Si i<\/span><span title=\"\">ntitola <strong><a href=\"https:\/\/afterres2050.solagro.org\/wp-content\/uploads\/2015\/11\/Solagro_afterres2050-v2-web.pdf\">Afterres 2050<\/a> <\/strong>ed \u00e8 consultato dalle autorit\u00e0 pubbliche interessate.<\/span> <\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"it\"><span title=\"\">Si parte da una condizione necessaria: la riduzione del nostro consumo di <strong>proteine animali<\/strong>.<\/span> <span title=\"\"><em><strong>Meno carne rossa<\/strong> (massimo 500 g \/ settimana), due prodotti lattiero-caseari al giorno anzich\u00e9 tre, come raccomandato da ANSES<\/em> (<a href=\"https:\/\/www.anses.fr\/en\">Agenzia nazionale per la sicurezza alimentare, l&#8217;ambiente e il lavoro<\/a>, ndr).<\/span> <span title=\"\">Nello stesso rapporto, un economista afferma che lo scenario potrebbe consentire il mantenimento di <strong>57.000 posti di lavoro in agricoltura entro il 2030.<\/strong><\/span><\/span><\/p>\n<p><em>La <strong>transizione ecologica<\/strong> \u00e8 un punto di svolta, non una rottura<\/em>, conclude lo scienziato Lionel Ranjard. <em>Dobbiamo fissare obiettivi per ottenere risultati ambientali ed economici e dobbiamo coinvolgere tutti. Dobbiamo sostituire la vendita di sostanze chimiche con la vendita di consulenza tecnica &#8211; lo chiedono gli agricoltori &#8211; e poi sviluppare canali di comunicazione adatti a diffondere le conoscenze.<\/em><\/p>\n<hr \/>\n<p><em>Questo articolo \u00e8 tradotto dal francese: l&#8217;originale \u00e8 <a href=\"https:\/\/magazine.laruchequiditoui.fr\/lagroecologie-explique-a-ma-mere\/\" target=\"_blank\" rel=\"noopener\">a questo link<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;agroecologia \u00e8 allo stesso tempo una disciplina scientifica, un movimento sociale e un insieme di pratiche agricole. \u00c8 l&#8217;ecologia adattata all&#8217;agricoltura. In effetti, \u00e8 l&#8217;agricoltura di domani, come ufficialmente riconosciuto dalle Nazioni Unite nel 2018. Le api, alleate alate dell&#8217;agroecologia. \u00a9Thomas Louapre Ma di cosa si tratta? L&#8217;agroecologia si basa sugli strumenti forniti dalla natura [&hellip;]<\/p>\n","protected":false},"author":188,"featured_media":51415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[503],"tags":[5407,5408,5296,5081,4938,4798],"class_list":["post-51409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricoltura-rigenerativa","tag-coltivazione","tag-permacultura","tag-agroecologia","tag-biologico","tag-fattoria","tag-agricoltura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;agroecologia \u00e8 la chiave per la transizione ecologica? - WTF<\/title>\n<meta name=\"description\" content=\"L&#039;agroecologia pu\u00f2 essere un&#039;ottima soluzione per restituire autonomia ai contadini e preservare l&#039;ambiente in cui viviamo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crowdfarming.com\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;agroecologia \u00e8 la chiave per la transizione ecologica? - WTF\" \/>\n<meta property=\"og:description\" content=\"L&#039;agroecologia pu\u00f2 essere un&#039;ottima soluzione per restituire autonomia ai contadini e preservare l&#039;ambiente in cui viviamo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/\" \/>\n<meta property=\"og:site_name\" content=\"WTF\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-03T12:41:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T20:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luca Fraioli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Fraioli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/\"},\"author\":{\"name\":\"Luca Fraioli\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/d651581724f117960329a1d48cdb3a1e\"},\"headline\":\"L&#8217;agroecologia \u00e8 la chiave per la transizione ecologica?\",\"datePublished\":\"2021-03-03T12:41:49+00:00\",\"dateModified\":\"2025-12-22T20:03:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/\"},\"wordCount\":1176,\"image\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/agroecologia-1024x683-1.jpg\",\"keywords\":[\"coltivazione\",\"permacultura\",\"agroecologia\",\"biologico\",\"fattoria\",\"agricoltura\"],\"articleSection\":[\"Agricoltura rigenerativa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/\",\"name\":\"L'agroecologia \u00e8 la chiave per la transizione ecologica? - WTF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/agroecologia-1024x683-1.jpg\",\"datePublished\":\"2021-03-03T12:41:49+00:00\",\"dateModified\":\"2025-12-22T20:03:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/d651581724f117960329a1d48cdb3a1e\"},\"description\":\"L'agroecologia pu\u00f2 essere un'ottima soluzione per restituire autonomia ai contadini e preservare l'ambiente in cui viviamo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/agroecologia-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/agroecologia-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/it\\\/what-the-field\\\/agricoltura-rigenerativa\\\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crowdfarming.com\\\/it\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;agroecologia \u00e8 la chiave per la transizione ecologica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTF\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/d651581724f117960329a1d48cdb3a1e\",\"name\":\"Luca Fraioli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g\",\"caption\":\"Luca Fraioli\"},\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/what-the-field\\\/it\\\/author\\\/lucafraioli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'agroecologia \u00e8 la chiave per la transizione ecologica? - WTF","description":"L'agroecologia pu\u00f2 essere un'ottima soluzione per restituire autonomia ai contadini e preservare l'ambiente in cui viviamo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crowdfarming.com\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/","og_locale":"it_IT","og_type":"article","og_title":"L'agroecologia \u00e8 la chiave per la transizione ecologica? - WTF","og_description":"L'agroecologia pu\u00f2 essere un'ottima soluzione per restituire autonomia ai contadini e preservare l'ambiente in cui viviamo.","og_url":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/","og_site_name":"WTF","article_published_time":"2021-03-03T12:41:49+00:00","article_modified_time":"2025-12-22T20:03:27+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg","type":"image\/jpeg"}],"author":"Luca Fraioli","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Luca Fraioli","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#article","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/"},"author":{"name":"Luca Fraioli","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/d651581724f117960329a1d48cdb3a1e"},"headline":"L&#8217;agroecologia \u00e8 la chiave per la transizione ecologica?","datePublished":"2021-03-03T12:41:49+00:00","dateModified":"2025-12-22T20:03:27+00:00","mainEntityOfPage":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/"},"wordCount":1176,"image":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg","keywords":["coltivazione","permacultura","agroecologia","biologico","fattoria","agricoltura"],"articleSection":["Agricoltura rigenerativa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/","url":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/","name":"L'agroecologia \u00e8 la chiave per la transizione ecologica? - WTF","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#primaryimage"},"image":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg","datePublished":"2021-03-03T12:41:49+00:00","dateModified":"2025-12-22T20:03:27+00:00","author":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/d651581724f117960329a1d48cdb3a1e"},"description":"L'agroecologia pu\u00f2 essere un'ottima soluzione per restituire autonomia ai contadini e preservare l'ambiente in cui viviamo.","breadcrumb":{"@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#primaryimage","url":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg","contentUrl":"https:\/\/laruchequiditoui.fr\/what-the-field\/wp-content\/uploads\/2021\/03\/agroecologia-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/laruchequiditoui.fr\/it\/what-the-field\/agricoltura-rigenerativa\/lagroecologia-e-la-chiave-per-la-transizione-ecologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crowdfarming.com\/it\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"L&#8217;agroecologia \u00e8 la chiave per la transizione ecologica?"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTF","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/d651581724f117960329a1d48cdb3a1e","name":"Luca Fraioli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/458c5a8f444c6b12d20b66dddf28c7e24a037268d82015331aad1b48510188a3?s=96&d=mm&r=g","caption":"Luca Fraioli"},"url":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/author\/lucafraioli\/"}]}},"_links":{"self":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/posts\/51409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/comments?post=51409"}],"version-history":[{"count":1,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/posts\/51409\/revisions"}],"predecessor-version":[{"id":51416,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/posts\/51409\/revisions\/51416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/media\/51415"}],"wp:attachment":[{"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/media?parent=51409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/categories?post=51409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laruchequiditoui.fr\/what-the-field\/it\/wp-json\/wp\/v2\/tags?post=51409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}